{"id":5187,"date":"2018-08-21T20:54:21","date_gmt":"2018-08-21T20:54:21","guid":{"rendered":"https:\/\/illaexperiencehotel.com\/por-que-merece-la-pena-visitar-quito-5-razones-para-visitar-quito-ecuador\/"},"modified":"2021-12-29T20:23:43","modified_gmt":"2021-12-29T20:23:43","slug":"por-que-merece-la-pena-visitar-quito-5-razones-para-visitar-quito-ecuador","status":"publish","type":"post","link":"https:\/\/illaexperiencehotel.com\/es\/por-que-merece-la-pena-visitar-quito-5-razones-para-visitar-quito-ecuador\/","title":{"rendered":"\u00bfPor qu\u00e9 merece la pena visitar Quito? 5 razones para visitar Quito, Ecuador"},"content":{"rendered":"<div>\n<div>\n<p>Vuelos baratos, desaf\u00edos, expansi\u00f3n de las fronteras son algunas de las razones para viajar y la lista seguir\u00e1 creciendo. Es evidente que encontrar un motivo para viajar no es una tarea dif\u00edcil.<\/p>\n<p>Una vez que se tiene la voluntad de viajar, entra en juego la segunda parte, la m\u00e1s dif\u00edcil: elegir el destino. Ahora bien, \u00bfc\u00f3mo elegir un destino cuando hay tantos, cada uno con sus propios encantos y ventajas?<\/p>\n<p>Te voy a facilitar el trabajo, si est\u00e1s leyendo esto entonces Quito es uno de los destinos tur\u00edsticos que se te ha metido en la cabeza. En lugar de aburrirte cont\u00e1ndote las principales atracciones, te contar\u00e9 aquellos atractivos que hacen de Quito algo diferente y que vale la pena visitar.<\/p>\n<\/div>\n<\/div>\n<div>\n<figure>\n<div><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/illaexperiencehotel.com\/wp-content\/uploads\/2018\/08\/quito-blog.jpg\" alt=\"Quito | Ecuador\" width=\"470\" height=\"250\"><\/div>\n<\/figure>\n<\/div>\n<div>\n<div>\n<p>&nbsp;<\/p>\n<p><strong>1. Quito tiene oficialmente el centro hist\u00f3rico m\u00e1s grande de Sudam\u00e9rica, y por lo tanto la mayor cantidad de vestigios hist\u00f3ricos que a\u00fan pueden ser apreciados hoy en d\u00eda<\/strong><br \/>\nAl tener el centro hist\u00f3rico m\u00e1s grande de Sudam\u00e9rica, eso significa que ver\u00e1s una gran cantidad de arquitectura colonial de hace cientos de a\u00f1os. Muchas casas, muchas calles han quedado tal y como estaban cuando los espa\u00f1oles vinieron a conquistarnos. No tendr\u00e1 que leerlo del folleto del Museo, sino que podr\u00e1 ir a esa calle especial, imaginar la historia por s\u00ed mismo y dejarse sumergir en un para\u00edso hist\u00f3rico.<\/p>\n<p><strong>2. El bello contraste de la naturaleza<\/strong><\/p>\n<p>Quito tiene una altitud de 2.850 metros y su altura permite ver los hermosos Andes que rodean la capital de Ecuador. Lo bonito es que te sentir\u00e1s como una persona peque\u00f1a en un mundo tan grande. Es incre\u00edble ver que est\u00e1s en medio de una ciudad de negocios y, sin embargo, est\u00e1s rodeado de majestuosos volcanes y monta\u00f1as. A diferencia de muchos otros lugares donde hay que levantarse a las 5 de la ma\u00f1ana para ver la monta\u00f1a, en Quito puedes hacerlo desde tu ventana y experimentar la magnitud de la naturaleza.<\/p>\n<p><strong>3. El pueblo<\/strong><\/p>\n<p>Los ecuatorianos son conocidos por su carisma, solidaridad y uni\u00f3n. Fortunately this has not changed throughout time. Ver\u00e1 familias juntas paseando por la calle, cafeter\u00edas llenas de parejas tomando un caf\u00e9 mientras comen el cl\u00e1sico bocadillo de cerdo, conocido como \u00abSanduche de Pernil\u00bb en la plaza principal de Carondelet. Ver\u00e1s que la gente vive feliz y comparte esa felicidad contigo. Cr\u00e9ame, no le consideraremos un extra\u00f1o y le saludaremos y le invitaremos a tener una charla r\u00e1pida sobre pol\u00edtica o el tiempo.<\/p>\n<p><strong>4. La cocina tradicional de Quito<\/strong><\/p>\n<p>S\u00e9 que cada lugar tendr\u00e1 su propia cocina tradicional, pero cr\u00e9eme que no querr\u00e1s perderte la cocina de Quito. Lo especial de nuestra cocina es que mantenemos vivas las tradiciones de la abuela. Las humitas, por ejemplo, son un tipo de pasta hecha enteramente de ma\u00edz que ha sido molido y luego mezclado con queso blando suavemente durante horas, estos son honestamente mi favorito personal. Sin embargo, luego est\u00e1 la deliciosa Espumilla. Un postre esponjoso a base de guayaba y huevo, cuya preparaci\u00f3n dura m\u00e1s de cinco horas. Adem\u00e1s, no hace falta ser rico ni elegante para degustar estas delicias, sino que puedes hacerlo con s\u00f3lo 1,50 d\u00f3lares, \u00bfa qu\u00e9 suena maravilloso?<\/p>\n<p><strong>5. Experimentar\u00e1s dos hemisferios al mismo tiempo<\/strong><\/p>\n<p>Seguramente habr\u00e1s o\u00eddo que Quito est\u00e1 situado en la mitad del mundo, pero \u00bfhas pensado alguna vez que podr\u00eda haber algo escondido detr\u00e1s? La respuesta es sencilla, s\u00ed. Al estar en dos hemisferios, experimentar\u00e1s diferentes fuerzas gravitacionales y presiones que desafiar\u00e1n tu cuerpo y tu mente de diferentes maneras. Su cuerpo ser\u00e1 desafiado con una tarea f\u00e1cil; intente caminar en l\u00ednea recta. Su mente, en cambio, se ver\u00e1 desafiada al contemplar un objeto delicado y fr\u00e1gil que se apoya perfectamente en un clavo. Cr\u00e9eme, estos momentos cambiar\u00e1n definitivamente tu forma de ver el mundo.<\/p>\n<p>Est\u00e1 claro que cinco razones no son suficientes para describir por qu\u00e9 Quito es un destino tan hermoso, pero seguro que son un peque\u00f1o empuj\u00f3n para que sigas pendiente de Quito. Aunque Ecuador pueda parecer un pa\u00eds peque\u00f1o, es precisamente su tama\u00f1o lo que lo hace m\u00e1s atractivo y con m\u00e1s secretos y lugares ocultos por encontrar. Te invito a que lo visites, Quito te iluminar\u00e1 el coraz\u00f3n y la mente. Garantizado!<\/p>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Vuelos baratos, desaf\u00edos, expansi\u00f3n de las fronteras son algunas de las razones para viajar y la lista seguir\u00e1 creciendo. Es evidente que encontrar un motivo para viajar no es una tarea dif\u00edcil. Una vez que se tiene la voluntad de viajar, entra en juego la segunda parte, la m\u00e1s dif\u00edcil: elegir el destino. Ahora bien, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":4298,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[2076],"tags":[],"class_list":["post-5187","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categorizar"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00bfPor qu\u00e9 merece la pena visitar Quito? 5 razones para visitar Quito, Ecuador - ILLA Experience hotel : luxury boutique hotel in Quito Ecuador : 5 star accommodation<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/illaexperiencehotel.com\/es\/por-que-merece-la-pena-visitar-quito-5-razones-para-visitar-quito-ecuador\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00bfPor qu\u00e9 merece la pena visitar Quito? 5 razones para visitar Quito, Ecuador - ILLA Experience hotel : luxury boutique hotel in Quito Ecuador : 5 star accommodation\" \/>\n<meta property=\"og:description\" content=\"Vuelos baratos, desaf\u00edos, expansi\u00f3n de las fronteras son algunas de las razones para viajar y la lista seguir\u00e1 creciendo. Es evidente que encontrar un motivo para viajar no es una tarea dif\u00edcil. Una vez que se tiene la voluntad de viajar, entra en juego la segunda parte, la m\u00e1s dif\u00edcil: elegir el destino. Ahora bien, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/illaexperiencehotel.com\/es\/por-que-merece-la-pena-visitar-quito-5-razones-para-visitar-quito-ecuador\/\" \/>\n<meta property=\"og:site_name\" content=\"ILLA Experience hotel : luxury boutique hotel in Quito Ecuador : 5 star accommodation\" \/>\n<meta property=\"article:published_time\" content=\"2018-08-21T20:54:21+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-12-29T20:23:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/illaexperiencehotel.com\/wp-content\/uploads\/2021\/12\/Quito-Panecillo-1024x680-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"680\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"illa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"illa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/illaexperiencehotel.com\\\/es\\\/por-que-merece-la-pena-visitar-quito-5-razones-para-visitar-quito-ecuador\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/illaexperiencehotel.com\\\/es\\\/por-que-merece-la-pena-visitar-quito-5-razones-para-visitar-quito-ecuador\\\/\"},\"author\":{\"name\":\"illa\",\"@id\":\"https:\\\/\\\/illaexperiencehotel.com\\\/#\\\/schema\\\/person\\\/61748114a58267edb47d32379ddb415a\"},\"headline\":\"\u00bfPor qu\u00e9 merece la pena visitar Quito? 5 razones para visitar Quito, Ecuador\",\"datePublished\":\"2018-08-21T20:54:21+00:00\",\"dateModified\":\"2021-12-29T20:23:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/illaexperiencehotel.com\\\/es\\\/por-que-merece-la-pena-visitar-quito-5-razones-para-visitar-quito-ecuador\\\/\"},\"wordCount\":765,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/illaexperiencehotel.com\\\/es\\\/por-que-merece-la-pena-visitar-quito-5-razones-para-visitar-quito-ecuador\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/illaexperiencehotel.com\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/Quito-Panecillo-1024x680-1.jpg\",\"articleSection\":[\"Sin categorizar\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/illaexperiencehotel.com\\\/es\\\/por-que-merece-la-pena-visitar-quito-5-razones-para-visitar-quito-ecuador\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/illaexperiencehotel.com\\\/es\\\/por-que-merece-la-pena-visitar-quito-5-razones-para-visitar-quito-ecuador\\\/\",\"url\":\"https:\\\/\\\/illaexperiencehotel.com\\\/es\\\/por-que-merece-la-pena-visitar-quito-5-razones-para-visitar-quito-ecuador\\\/\",\"name\":\"\u00bfPor qu\u00e9 merece la pena visitar Quito? 5 razones para visitar Quito, Ecuador - ILLA Experience hotel : luxury boutique hotel in Quito Ecuador : 5 star accommodation\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/illaexperiencehotel.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/illaexperiencehotel.com\\\/es\\\/por-que-merece-la-pena-visitar-quito-5-razones-para-visitar-quito-ecuador\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/illaexperiencehotel.com\\\/es\\\/por-que-merece-la-pena-visitar-quito-5-razones-para-visitar-quito-ecuador\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/illaexperiencehotel.com\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/Quito-Panecillo-1024x680-1.jpg\",\"datePublished\":\"2018-08-21T20:54:21+00:00\",\"dateModified\":\"2021-12-29T20:23:43+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/illaexperiencehotel.com\\\/#\\\/schema\\\/person\\\/61748114a58267edb47d32379ddb415a\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/illaexperiencehotel.com\\\/es\\\/por-que-merece-la-pena-visitar-quito-5-razones-para-visitar-quito-ecuador\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/illaexperiencehotel.com\\\/es\\\/por-que-merece-la-pena-visitar-quito-5-razones-para-visitar-quito-ecuador\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/illaexperiencehotel.com\\\/es\\\/por-que-merece-la-pena-visitar-quito-5-razones-para-visitar-quito-ecuador\\\/#primaryimage\",\"url\":\"https:\\\/\\\/illaexperiencehotel.com\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/Quito-Panecillo-1024x680-1.jpg\",\"contentUrl\":\"https:\\\/\\\/illaexperiencehotel.com\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/Quito-Panecillo-1024x680-1.jpg\",\"width\":1024,\"height\":680},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/illaexperiencehotel.com\\\/es\\\/por-que-merece-la-pena-visitar-quito-5-razones-para-visitar-quito-ecuador\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/illaexperiencehotel.com\\\/es\\\/inicio-illa-experience-hotel\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00bfPor qu\u00e9 merece la pena visitar Quito? 5 razones para visitar Quito, Ecuador\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/illaexperiencehotel.com\\\/#website\",\"url\":\"https:\\\/\\\/illaexperiencehotel.com\\\/\",\"name\":\"ILLA Experience hotel : luxury boutique hotel in Quito Ecuador : 5 star accommodation\",\"description\":\"ILLA Experience hotel : luxury  boutique hotel in Quito Ecuador : 5 star accommodation\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/illaexperiencehotel.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/illaexperiencehotel.com\\\/#\\\/schema\\\/person\\\/61748114a58267edb47d32379ddb415a\",\"name\":\"illa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ba738f2640a90763f57c5cf1ac0992debbb5df39a5c1b492fc174f782a64b71f?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ba738f2640a90763f57c5cf1ac0992debbb5df39a5c1b492fc174f782a64b71f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ba738f2640a90763f57c5cf1ac0992debbb5df39a5c1b492fc174f782a64b71f?s=96&d=mm&r=g\",\"caption\":\"illa\"},\"url\":\"https:\\\/\\\/illaexperiencehotel.com\\\/es\\\/author\\\/illa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00bfPor qu\u00e9 merece la pena visitar Quito? 5 razones para visitar Quito, Ecuador - ILLA Experience hotel : luxury boutique hotel in Quito Ecuador : 5 star accommodation","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/illaexperiencehotel.com\/es\/por-que-merece-la-pena-visitar-quito-5-razones-para-visitar-quito-ecuador\/","og_locale":"es_ES","og_type":"article","og_title":"\u00bfPor qu\u00e9 merece la pena visitar Quito? 5 razones para visitar Quito, Ecuador - ILLA Experience hotel : luxury boutique hotel in Quito Ecuador : 5 star accommodation","og_description":"Vuelos baratos, desaf\u00edos, expansi\u00f3n de las fronteras son algunas de las razones para viajar y la lista seguir\u00e1 creciendo. Es evidente que encontrar un motivo para viajar no es una tarea dif\u00edcil. Una vez que se tiene la voluntad de viajar, entra en juego la segunda parte, la m\u00e1s dif\u00edcil: elegir el destino. Ahora bien, [&hellip;]","og_url":"https:\/\/illaexperiencehotel.com\/es\/por-que-merece-la-pena-visitar-quito-5-razones-para-visitar-quito-ecuador\/","og_site_name":"ILLA Experience hotel : luxury boutique hotel in Quito Ecuador : 5 star accommodation","article_published_time":"2018-08-21T20:54:21+00:00","article_modified_time":"2021-12-29T20:23:43+00:00","og_image":[{"width":1024,"height":680,"url":"https:\/\/illaexperiencehotel.com\/wp-content\/uploads\/2021\/12\/Quito-Panecillo-1024x680-1.jpg","type":"image\/jpeg"}],"author":"illa","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"illa","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/illaexperiencehotel.com\/es\/por-que-merece-la-pena-visitar-quito-5-razones-para-visitar-quito-ecuador\/#article","isPartOf":{"@id":"https:\/\/illaexperiencehotel.com\/es\/por-que-merece-la-pena-visitar-quito-5-razones-para-visitar-quito-ecuador\/"},"author":{"name":"illa","@id":"https:\/\/illaexperiencehotel.com\/#\/schema\/person\/61748114a58267edb47d32379ddb415a"},"headline":"\u00bfPor qu\u00e9 merece la pena visitar Quito? 5 razones para visitar Quito, Ecuador","datePublished":"2018-08-21T20:54:21+00:00","dateModified":"2021-12-29T20:23:43+00:00","mainEntityOfPage":{"@id":"https:\/\/illaexperiencehotel.com\/es\/por-que-merece-la-pena-visitar-quito-5-razones-para-visitar-quito-ecuador\/"},"wordCount":765,"commentCount":0,"image":{"@id":"https:\/\/illaexperiencehotel.com\/es\/por-que-merece-la-pena-visitar-quito-5-razones-para-visitar-quito-ecuador\/#primaryimage"},"thumbnailUrl":"https:\/\/illaexperiencehotel.com\/wp-content\/uploads\/2021\/12\/Quito-Panecillo-1024x680-1.jpg","articleSection":["Sin categorizar"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/illaexperiencehotel.com\/es\/por-que-merece-la-pena-visitar-quito-5-razones-para-visitar-quito-ecuador\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/illaexperiencehotel.com\/es\/por-que-merece-la-pena-visitar-quito-5-razones-para-visitar-quito-ecuador\/","url":"https:\/\/illaexperiencehotel.com\/es\/por-que-merece-la-pena-visitar-quito-5-razones-para-visitar-quito-ecuador\/","name":"\u00bfPor qu\u00e9 merece la pena visitar Quito? 5 razones para visitar Quito, Ecuador - ILLA Experience hotel : luxury boutique hotel in Quito Ecuador : 5 star accommodation","isPartOf":{"@id":"https:\/\/illaexperiencehotel.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/illaexperiencehotel.com\/es\/por-que-merece-la-pena-visitar-quito-5-razones-para-visitar-quito-ecuador\/#primaryimage"},"image":{"@id":"https:\/\/illaexperiencehotel.com\/es\/por-que-merece-la-pena-visitar-quito-5-razones-para-visitar-quito-ecuador\/#primaryimage"},"thumbnailUrl":"https:\/\/illaexperiencehotel.com\/wp-content\/uploads\/2021\/12\/Quito-Panecillo-1024x680-1.jpg","datePublished":"2018-08-21T20:54:21+00:00","dateModified":"2021-12-29T20:23:43+00:00","author":{"@id":"https:\/\/illaexperiencehotel.com\/#\/schema\/person\/61748114a58267edb47d32379ddb415a"},"breadcrumb":{"@id":"https:\/\/illaexperiencehotel.com\/es\/por-que-merece-la-pena-visitar-quito-5-razones-para-visitar-quito-ecuador\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/illaexperiencehotel.com\/es\/por-que-merece-la-pena-visitar-quito-5-razones-para-visitar-quito-ecuador\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/illaexperiencehotel.com\/es\/por-que-merece-la-pena-visitar-quito-5-razones-para-visitar-quito-ecuador\/#primaryimage","url":"https:\/\/illaexperiencehotel.com\/wp-content\/uploads\/2021\/12\/Quito-Panecillo-1024x680-1.jpg","contentUrl":"https:\/\/illaexperiencehotel.com\/wp-content\/uploads\/2021\/12\/Quito-Panecillo-1024x680-1.jpg","width":1024,"height":680},{"@type":"BreadcrumbList","@id":"https:\/\/illaexperiencehotel.com\/es\/por-que-merece-la-pena-visitar-quito-5-razones-para-visitar-quito-ecuador\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/illaexperiencehotel.com\/es\/inicio-illa-experience-hotel\/"},{"@type":"ListItem","position":2,"name":"\u00bfPor qu\u00e9 merece la pena visitar Quito? 5 razones para visitar Quito, Ecuador"}]},{"@type":"WebSite","@id":"https:\/\/illaexperiencehotel.com\/#website","url":"https:\/\/illaexperiencehotel.com\/","name":"ILLA Experience hotel : luxury boutique hotel in Quito Ecuador : 5 star accommodation","description":"ILLA Experience hotel : luxury  boutique hotel in Quito Ecuador : 5 star accommodation","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/illaexperiencehotel.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/illaexperiencehotel.com\/#\/schema\/person\/61748114a58267edb47d32379ddb415a","name":"illa","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/ba738f2640a90763f57c5cf1ac0992debbb5df39a5c1b492fc174f782a64b71f?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ba738f2640a90763f57c5cf1ac0992debbb5df39a5c1b492fc174f782a64b71f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ba738f2640a90763f57c5cf1ac0992debbb5df39a5c1b492fc174f782a64b71f?s=96&d=mm&r=g","caption":"illa"},"url":"https:\/\/illaexperiencehotel.com\/es\/author\/illa\/"}]}},"_links":{"self":[{"href":"https:\/\/illaexperiencehotel.com\/es\/wp-json\/wp\/v2\/posts\/5187","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/illaexperiencehotel.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/illaexperiencehotel.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/illaexperiencehotel.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/illaexperiencehotel.com\/es\/wp-json\/wp\/v2\/comments?post=5187"}],"version-history":[{"count":0,"href":"https:\/\/illaexperiencehotel.com\/es\/wp-json\/wp\/v2\/posts\/5187\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/illaexperiencehotel.com\/es\/wp-json\/wp\/v2\/media\/4298"}],"wp:attachment":[{"href":"https:\/\/illaexperiencehotel.com\/es\/wp-json\/wp\/v2\/media?parent=5187"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/illaexperiencehotel.com\/es\/wp-json\/wp\/v2\/categories?post=5187"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/illaexperiencehotel.com\/es\/wp-json\/wp\/v2\/tags?post=5187"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}