{"id":5129,"date":"2018-06-01T19:48:50","date_gmt":"2018-06-01T19:48:50","guid":{"rendered":"https:\/\/illaexperiencehotel.com\/unete-a-la-comunidad-de-san-marcos-en-la-procesion-de-la-soledad-de-maria\/"},"modified":"2021-12-29T20:13:20","modified_gmt":"2021-12-29T20:13:20","slug":"unete-a-la-comunidad-de-san-marcos-en-la-procesion-de-la-soledad-de-maria","status":"publish","type":"post","link":"https:\/\/illaexperiencehotel.com\/es\/unete-a-la-comunidad-de-san-marcos-en-la-procesion-de-la-soledad-de-maria\/","title":{"rendered":"\u00danete a la comunidad de San Marcos en la procesi\u00f3n de la soledad de Mar\u00eda"},"content":{"rendered":"<div>\n<div>\n<div>\n<div>\n<div>\n<div>\n<div>\n<p>La historia ecuatoriana est\u00e1 estrechamente relacionada con la religi\u00f3n cat\u00f3lica y la evangelizaci\u00f3n de los ind\u00edgenas en el per\u00edodo colonial. Por lo tanto, Ecuador es un pa\u00eds muy religioso con muchas festividades y tradiciones relacionadas con el catolicismo. Por eso la Semana Santa es una de las \u00e9pocas del a\u00f1o en las que los lugare\u00f1os tienen la oportunidad de expresar su devoci\u00f3n de forma masiva.<\/p>\n<p>Durante esta semana, Quito entre otras ciudades del Ecuador tiene muchas expresiones religiosas. Efectivamente, es uno muy conocido, que es la Procesi\u00f3n de Jes\u00fas del Gran Poder (Jes\u00fas del Gran Poder) que se realiza durante el Viernes Santo en las calles del centro de la ciudad de Quito. Es una tradici\u00f3n antigua y muy popular tanto para los lugare\u00f1os como para los viajeros; sin embargo, hoy en d\u00eda est\u00e1 muy concurrido.<\/p>\n<\/div>\n<\/div>\n<div>\n<div>\n<p>Sin embargo, hay otras expresiones seguidas por peque\u00f1as comunidades que tambi\u00e9n muestran la importancia de las tradiciones religiosas durante la Semana Santa. San Marcos, por ejemplo, es una de estas comunidades. Todos los a\u00f1os los devotos pasean a la Virgen de Dolores por las calles de San Marco, imagen del siglo XVI que representa a la Escuela Quite\u00f1a. Para los locales, la procesi\u00f3n del S\u00e1bado Santo, que este 2018 es el 31 de marzo, es la forma de recordar y sentir a trav\u00e9s de la m\u00fasica la tristeza de la muerte de Jesucristo para luego terminar con la alegr\u00eda de la resurrecci\u00f3n de \u00e9l.<\/p>\n<p>San Marcos es un barrio art\u00edstico tradicional que se encuentra muy cerca del centro de la ciudad (5 minutos caminando); sin embargo, todav\u00eda est\u00e1 reflejando y viviendo de una manera muy tradicional porque se mantuvo aislada del centro de la ciudad durante a\u00f1os. Por eso, muchos lugare\u00f1os siempre dicen que van al centro de la ciudad como un lugar lejano aunque est\u00e9n a solo unas cuadras de distancia.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div>\n<div>\n<div>\n<div>\n<div>\n<div>\n<div>\n<p>Ruta de la Procesi\u00f3n en San Marcos<\/p>\n<\/div>\n<\/div>\n<div>\n<figure>\n<div><img decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/illaexperiencehotel.com\/wp-content\/uploads\/2018\/03\/Procession-route-in-San-Marcos.jpg\"><\/div>\n<\/figure>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div>\n<div>\n<div>\n<div>\n<div>\n<p>Esa es la raz\u00f3n por la que Illa Experience Hotel invita tanto a locales como a visitantes a unirse a ellos en esta procesi\u00f3n. No hay mejor manera de acercarse a una expresi\u00f3n aut\u00e9ntica y significativa de la creencia religiosa y la pasi\u00f3n de una congregaci\u00f3n local, fuera de los caminos tur\u00edsticos habituales.<\/p>\n<p>Asimismo, Illa Hotel abre sus puertas a aquellos visitantes que quieran vivir una mezcla de tradici\u00f3n y gastronom\u00eda \u00fanica en el Restaurante Nuema. Solo para este 31 de marzo Nuema ofrece un almuerzo con men\u00fa de siete tiempos pensado para transmitir los sabores y costumbres que representan al Ecuador durante la Semana Santa.<\/p>\n<\/div>\n<\/div>\n<div>\n<div>\n<p>Ven a Illa Experience Hotel, disfruta de un almuerzo memorable en el Restaurante Nuema, y \u200b\u200bluego \u00fanete a la comunidad de San Marcos en la procesi\u00f3n de la Virgen de Dolores desde las 16h00 hasta las 18h00, y vive este evento como un local.<\/p>\n<p>Si desea organizar su almuerzo en Illa y obtener m\u00e1s informaci\u00f3n sobre el evento, comun\u00edquese con Illa Experience Hotel en <a href=\"mailto:sales@illaexperiencehotel.com\">sales@illaexperiencehotel.com<\/a> o llame al + 593\u20132\u2013 395 7010.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>La historia ecuatoriana est\u00e1 estrechamente relacionada con la religi\u00f3n cat\u00f3lica y la evangelizaci\u00f3n de los ind\u00edgenas en el per\u00edodo colonial. Por lo tanto, Ecuador es un pa\u00eds muy religioso con muchas festividades y tradiciones relacionadas con el catolicismo. Por eso la Semana Santa es una de las \u00e9pocas del a\u00f1o en las que los lugare\u00f1os [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":3931,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[2076],"tags":[],"class_list":["post-5129","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categorizar"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00danete a la comunidad de San Marcos en la procesi\u00f3n de la soledad de Mar\u00eda - ILLA Experience hotel : luxury boutique hotel in Quito Ecuador : 5 star accommodation<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/illaexperiencehotel.com\/es\/unete-a-la-comunidad-de-san-marcos-en-la-procesion-de-la-soledad-de-maria\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00danete a la comunidad de San Marcos en la procesi\u00f3n de la soledad de Mar\u00eda - ILLA Experience hotel : luxury boutique hotel in Quito Ecuador : 5 star accommodation\" \/>\n<meta property=\"og:description\" content=\"La historia ecuatoriana est\u00e1 estrechamente relacionada con la religi\u00f3n cat\u00f3lica y la evangelizaci\u00f3n de los ind\u00edgenas en el per\u00edodo colonial. Por lo tanto, Ecuador es un pa\u00eds muy religioso con muchas festividades y tradiciones relacionadas con el catolicismo. Por eso la Semana Santa es una de las \u00e9pocas del a\u00f1o en las que los lugare\u00f1os [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/illaexperiencehotel.com\/es\/unete-a-la-comunidad-de-san-marcos-en-la-procesion-de-la-soledad-de-maria\/\" \/>\n<meta property=\"og:site_name\" content=\"ILLA Experience hotel : luxury boutique hotel in Quito Ecuador : 5 star accommodation\" \/>\n<meta property=\"article:published_time\" content=\"2018-06-01T19:48:50+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-12-29T20:13:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/illaexperiencehotel.com\/wp-content\/uploads\/2018\/03\/illa-experience-hotel-holy-week.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1033\" \/>\n\t<meta property=\"og:image:height\" content=\"341\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"illa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"illa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/illaexperiencehotel.com\\\/es\\\/unete-a-la-comunidad-de-san-marcos-en-la-procesion-de-la-soledad-de-maria\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/illaexperiencehotel.com\\\/es\\\/unete-a-la-comunidad-de-san-marcos-en-la-procesion-de-la-soledad-de-maria\\\/\"},\"author\":{\"name\":\"illa\",\"@id\":\"https:\\\/\\\/illaexperiencehotel.com\\\/#\\\/schema\\\/person\\\/61748114a58267edb47d32379ddb415a\"},\"headline\":\"\u00danete a la comunidad de San Marcos en la procesi\u00f3n de la soledad de Mar\u00eda\",\"datePublished\":\"2018-06-01T19:48:50+00:00\",\"dateModified\":\"2021-12-29T20:13:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/illaexperiencehotel.com\\\/es\\\/unete-a-la-comunidad-de-san-marcos-en-la-procesion-de-la-soledad-de-maria\\\/\"},\"wordCount\":548,\"image\":{\"@id\":\"https:\\\/\\\/illaexperiencehotel.com\\\/es\\\/unete-a-la-comunidad-de-san-marcos-en-la-procesion-de-la-soledad-de-maria\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/illaexperiencehotel.com\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/illa-experience-hotel-holy-week.jpg\",\"articleSection\":[\"Sin categorizar\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/illaexperiencehotel.com\\\/es\\\/unete-a-la-comunidad-de-san-marcos-en-la-procesion-de-la-soledad-de-maria\\\/\",\"url\":\"https:\\\/\\\/illaexperiencehotel.com\\\/es\\\/unete-a-la-comunidad-de-san-marcos-en-la-procesion-de-la-soledad-de-maria\\\/\",\"name\":\"\u00danete a la comunidad de San Marcos en la procesi\u00f3n de la soledad de Mar\u00eda - ILLA Experience hotel : luxury boutique hotel in Quito Ecuador : 5 star accommodation\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/illaexperiencehotel.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/illaexperiencehotel.com\\\/es\\\/unete-a-la-comunidad-de-san-marcos-en-la-procesion-de-la-soledad-de-maria\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/illaexperiencehotel.com\\\/es\\\/unete-a-la-comunidad-de-san-marcos-en-la-procesion-de-la-soledad-de-maria\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/illaexperiencehotel.com\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/illa-experience-hotel-holy-week.jpg\",\"datePublished\":\"2018-06-01T19:48:50+00:00\",\"dateModified\":\"2021-12-29T20:13:20+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/illaexperiencehotel.com\\\/#\\\/schema\\\/person\\\/61748114a58267edb47d32379ddb415a\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/illaexperiencehotel.com\\\/es\\\/unete-a-la-comunidad-de-san-marcos-en-la-procesion-de-la-soledad-de-maria\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/illaexperiencehotel.com\\\/es\\\/unete-a-la-comunidad-de-san-marcos-en-la-procesion-de-la-soledad-de-maria\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/illaexperiencehotel.com\\\/es\\\/unete-a-la-comunidad-de-san-marcos-en-la-procesion-de-la-soledad-de-maria\\\/#primaryimage\",\"url\":\"https:\\\/\\\/illaexperiencehotel.com\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/illa-experience-hotel-holy-week.jpg\",\"contentUrl\":\"https:\\\/\\\/illaexperiencehotel.com\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/illa-experience-hotel-holy-week.jpg\",\"width\":1033,\"height\":341},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/illaexperiencehotel.com\\\/es\\\/unete-a-la-comunidad-de-san-marcos-en-la-procesion-de-la-soledad-de-maria\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/illaexperiencehotel.com\\\/es\\\/inicio-illa-experience-hotel\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00danete a la comunidad de San Marcos en la procesi\u00f3n de la soledad de Mar\u00eda\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/illaexperiencehotel.com\\\/#website\",\"url\":\"https:\\\/\\\/illaexperiencehotel.com\\\/\",\"name\":\"ILLA Experience hotel : luxury boutique hotel in Quito Ecuador : 5 star accommodation\",\"description\":\"ILLA Experience hotel : luxury  boutique hotel in Quito Ecuador : 5 star accommodation\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/illaexperiencehotel.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/illaexperiencehotel.com\\\/#\\\/schema\\\/person\\\/61748114a58267edb47d32379ddb415a\",\"name\":\"illa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ba738f2640a90763f57c5cf1ac0992debbb5df39a5c1b492fc174f782a64b71f?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ba738f2640a90763f57c5cf1ac0992debbb5df39a5c1b492fc174f782a64b71f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ba738f2640a90763f57c5cf1ac0992debbb5df39a5c1b492fc174f782a64b71f?s=96&d=mm&r=g\",\"caption\":\"illa\"},\"url\":\"https:\\\/\\\/illaexperiencehotel.com\\\/es\\\/author\\\/illa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00danete a la comunidad de San Marcos en la procesi\u00f3n de la soledad de Mar\u00eda - ILLA Experience hotel : luxury boutique hotel in Quito Ecuador : 5 star accommodation","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/illaexperiencehotel.com\/es\/unete-a-la-comunidad-de-san-marcos-en-la-procesion-de-la-soledad-de-maria\/","og_locale":"es_ES","og_type":"article","og_title":"\u00danete a la comunidad de San Marcos en la procesi\u00f3n de la soledad de Mar\u00eda - ILLA Experience hotel : luxury boutique hotel in Quito Ecuador : 5 star accommodation","og_description":"La historia ecuatoriana est\u00e1 estrechamente relacionada con la religi\u00f3n cat\u00f3lica y la evangelizaci\u00f3n de los ind\u00edgenas en el per\u00edodo colonial. Por lo tanto, Ecuador es un pa\u00eds muy religioso con muchas festividades y tradiciones relacionadas con el catolicismo. Por eso la Semana Santa es una de las \u00e9pocas del a\u00f1o en las que los lugare\u00f1os [&hellip;]","og_url":"https:\/\/illaexperiencehotel.com\/es\/unete-a-la-comunidad-de-san-marcos-en-la-procesion-de-la-soledad-de-maria\/","og_site_name":"ILLA Experience hotel : luxury boutique hotel in Quito Ecuador : 5 star accommodation","article_published_time":"2018-06-01T19:48:50+00:00","article_modified_time":"2021-12-29T20:13:20+00:00","og_image":[{"width":1033,"height":341,"url":"https:\/\/illaexperiencehotel.com\/wp-content\/uploads\/2018\/03\/illa-experience-hotel-holy-week.jpg","type":"image\/jpeg"}],"author":"illa","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"illa","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/illaexperiencehotel.com\/es\/unete-a-la-comunidad-de-san-marcos-en-la-procesion-de-la-soledad-de-maria\/#article","isPartOf":{"@id":"https:\/\/illaexperiencehotel.com\/es\/unete-a-la-comunidad-de-san-marcos-en-la-procesion-de-la-soledad-de-maria\/"},"author":{"name":"illa","@id":"https:\/\/illaexperiencehotel.com\/#\/schema\/person\/61748114a58267edb47d32379ddb415a"},"headline":"\u00danete a la comunidad de San Marcos en la procesi\u00f3n de la soledad de Mar\u00eda","datePublished":"2018-06-01T19:48:50+00:00","dateModified":"2021-12-29T20:13:20+00:00","mainEntityOfPage":{"@id":"https:\/\/illaexperiencehotel.com\/es\/unete-a-la-comunidad-de-san-marcos-en-la-procesion-de-la-soledad-de-maria\/"},"wordCount":548,"image":{"@id":"https:\/\/illaexperiencehotel.com\/es\/unete-a-la-comunidad-de-san-marcos-en-la-procesion-de-la-soledad-de-maria\/#primaryimage"},"thumbnailUrl":"https:\/\/illaexperiencehotel.com\/wp-content\/uploads\/2018\/03\/illa-experience-hotel-holy-week.jpg","articleSection":["Sin categorizar"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/illaexperiencehotel.com\/es\/unete-a-la-comunidad-de-san-marcos-en-la-procesion-de-la-soledad-de-maria\/","url":"https:\/\/illaexperiencehotel.com\/es\/unete-a-la-comunidad-de-san-marcos-en-la-procesion-de-la-soledad-de-maria\/","name":"\u00danete a la comunidad de San Marcos en la procesi\u00f3n de la soledad de Mar\u00eda - ILLA Experience hotel : luxury boutique hotel in Quito Ecuador : 5 star accommodation","isPartOf":{"@id":"https:\/\/illaexperiencehotel.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/illaexperiencehotel.com\/es\/unete-a-la-comunidad-de-san-marcos-en-la-procesion-de-la-soledad-de-maria\/#primaryimage"},"image":{"@id":"https:\/\/illaexperiencehotel.com\/es\/unete-a-la-comunidad-de-san-marcos-en-la-procesion-de-la-soledad-de-maria\/#primaryimage"},"thumbnailUrl":"https:\/\/illaexperiencehotel.com\/wp-content\/uploads\/2018\/03\/illa-experience-hotel-holy-week.jpg","datePublished":"2018-06-01T19:48:50+00:00","dateModified":"2021-12-29T20:13:20+00:00","author":{"@id":"https:\/\/illaexperiencehotel.com\/#\/schema\/person\/61748114a58267edb47d32379ddb415a"},"breadcrumb":{"@id":"https:\/\/illaexperiencehotel.com\/es\/unete-a-la-comunidad-de-san-marcos-en-la-procesion-de-la-soledad-de-maria\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/illaexperiencehotel.com\/es\/unete-a-la-comunidad-de-san-marcos-en-la-procesion-de-la-soledad-de-maria\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/illaexperiencehotel.com\/es\/unete-a-la-comunidad-de-san-marcos-en-la-procesion-de-la-soledad-de-maria\/#primaryimage","url":"https:\/\/illaexperiencehotel.com\/wp-content\/uploads\/2018\/03\/illa-experience-hotel-holy-week.jpg","contentUrl":"https:\/\/illaexperiencehotel.com\/wp-content\/uploads\/2018\/03\/illa-experience-hotel-holy-week.jpg","width":1033,"height":341},{"@type":"BreadcrumbList","@id":"https:\/\/illaexperiencehotel.com\/es\/unete-a-la-comunidad-de-san-marcos-en-la-procesion-de-la-soledad-de-maria\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/illaexperiencehotel.com\/es\/inicio-illa-experience-hotel\/"},{"@type":"ListItem","position":2,"name":"\u00danete a la comunidad de San Marcos en la procesi\u00f3n de la soledad de Mar\u00eda"}]},{"@type":"WebSite","@id":"https:\/\/illaexperiencehotel.com\/#website","url":"https:\/\/illaexperiencehotel.com\/","name":"ILLA Experience hotel : luxury boutique hotel in Quito Ecuador : 5 star accommodation","description":"ILLA Experience hotel : luxury  boutique hotel in Quito Ecuador : 5 star accommodation","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/illaexperiencehotel.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/illaexperiencehotel.com\/#\/schema\/person\/61748114a58267edb47d32379ddb415a","name":"illa","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/ba738f2640a90763f57c5cf1ac0992debbb5df39a5c1b492fc174f782a64b71f?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ba738f2640a90763f57c5cf1ac0992debbb5df39a5c1b492fc174f782a64b71f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ba738f2640a90763f57c5cf1ac0992debbb5df39a5c1b492fc174f782a64b71f?s=96&d=mm&r=g","caption":"illa"},"url":"https:\/\/illaexperiencehotel.com\/es\/author\/illa\/"}]}},"_links":{"self":[{"href":"https:\/\/illaexperiencehotel.com\/es\/wp-json\/wp\/v2\/posts\/5129","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/illaexperiencehotel.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/illaexperiencehotel.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/illaexperiencehotel.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/illaexperiencehotel.com\/es\/wp-json\/wp\/v2\/comments?post=5129"}],"version-history":[{"count":0,"href":"https:\/\/illaexperiencehotel.com\/es\/wp-json\/wp\/v2\/posts\/5129\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/illaexperiencehotel.com\/es\/wp-json\/wp\/v2\/media\/3931"}],"wp:attachment":[{"href":"https:\/\/illaexperiencehotel.com\/es\/wp-json\/wp\/v2\/media?parent=5129"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/illaexperiencehotel.com\/es\/wp-json\/wp\/v2\/categories?post=5129"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/illaexperiencehotel.com\/es\/wp-json\/wp\/v2\/tags?post=5129"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}