{"id":5059,"date":"2018-02-12T03:55:35","date_gmt":"2018-02-12T03:55:35","guid":{"rendered":"https:\/\/illaexperiencehotel.com\/fanesca\/"},"modified":"2021-12-29T20:04:18","modified_gmt":"2021-12-29T20:04:18","slug":"fanesca","status":"publish","type":"post","link":"https:\/\/illaexperiencehotel.com\/es\/fanesca\/","title":{"rendered":"Fanesca"},"content":{"rendered":"<div>\n<div>\n<div>\n<div>\n<div>\n<div>\n<figure>\n<div><\/div>\n<\/figure>\n<\/div>\n<div>\n<div>\n<p>La fanesca es el plato del men\u00fa festivo familiar del domingo de Pascua. Tambi\u00e9n puedes encontrarlo servido como plato especial de temporada en restaurantes y ferias gastron\u00f3micas. La fanesca es una sopa abundante hecha a base de granos tiernos y pescado seco. Para algunos, puede ser un gusto adquirido, pero para la mayor\u00eda de los ecuatorianos, es una tradici\u00f3n navide\u00f1a esencial.<\/p>\n<p>La historia de Fanesca, como la mayor\u00eda de las pr\u00e1cticas culturales aqu\u00ed en Ecuador, ilustra la mezcla de tradici\u00f3n prehisp\u00e1nica y cat\u00f3lica. Los habitantes de Quito antes de la conquista, celebraron el Mushuc Nina, el d\u00eda del Fuego Nuevo, como una forma de reconocer el Equinoccio de Primavera en marzo.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div>\n<div>\n<div>\n<div>\n<div>\n<div>\n<figure>\n<div><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/illaexperiencehotel.com\/wp-content\/uploads\/2018\/03\/fanesca-ecuador2.jpg\" alt=\"Fanesca\" width=\"464\" height=\"341\"><\/div>\n<\/figure>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div>\n<div>\n<div>\n<div>\n<div>\n<p>En Kichwa, este platillo, elaborado con granos tiernos cocidos con chile y hierbas, se llamaba \u00abuchucuta\u00bb. Inclu\u00eda guisantes, habas, <a href=\"https:\/\/illaexperiencehotel.com\/es\/guia-para-nuestras-comidas-deliciosas-y-exoticas\/\">mellocos<\/a>(una especie de papa andina diminuta), choclo (ma\u00edz con almid\u00f3n), frijoles y calabaza. Todos los alimentos que se cosecharon en esta temporada, desde febrero hasta la celebraci\u00f3n de Pawcar Raymi. Algunos creen que el plato de uchucuta tradicionalmente habr\u00eda estado acompa\u00f1ado de un cuy salvaje asado.<\/p>\n<p><img decoding=\"async\" class=\"alignleft\" src=\"https:\/\/illaexperiencehotel.com\/wp-content\/uploads\/2018\/03\/fanesca-ecuador3.jpg\" alt=\"Fanesca-ingredientes\" width=\"464\" height=\"341\">Durante la era colonial, los espa\u00f1oles utilizaron muchas pr\u00e1cticas y s\u00edmbolos ind\u00edgenas, que se combinaron con creencias y pr\u00e1cticas cat\u00f3licas para formar una religi\u00f3n y cultura \u00fanica y sincr\u00e9tica. Uchucuta no se libr\u00f3 de esta influencia: se integr\u00f3 a la celebraci\u00f3n de la Semana Santa, y el sufrimiento, muerte y resurrecci\u00f3n de Jes\u00fas se fusion\u00f3 con las celebraciones de la cosecha prehisp\u00e1nica. Posteriormente se agregaron los ingredientes de pescado y queso.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div>\n<div>\n<div>\n<div>\n<div>\n<div>\n<p>El plato se llam\u00f3 entonces fanesca, y su preparaci\u00f3n se relacion\u00f3 con el simbolismo cristiano. Ahora se dec\u00eda que los doce granos representaban a los doce disc\u00edpulos y las doce tribus de Israel, llevando a la fanesca a una narrativa milenaria sobre el cumplimiento de las profec\u00edas b\u00edblicas. El bacalao seco y salado (bacalao) representa al mismo Jes\u00fas. Algunos dicen que cada uno de los granos simboliza una figura espec\u00edfica en la fe cat\u00f3lica.<\/p>\n<p>El primer libro de cocina impreso en Quito, que se remonta a la posesi\u00f3n de Pablo Sanz en 1882, inclu\u00eda, por supuesto, una receta para la fanesca, que se estaba convirtiendo en est\u00e1ndar en todo el pa\u00eds:<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div>\n<div>\n<div>\n<div>\n<div>\n<div>\n<figure>\n<div><img decoding=\"async\" class=\"alignright\" src=\"https:\/\/illaexperiencehotel.com\/wp-content\/uploads\/2018\/03\/fanesca-ecuador4.jpg\" alt=\"fanesca-quito\" width=\"464\" height=\"341\"><\/div>\n<\/figure>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div>\n<div>\n<div>\n<div>\n<div>\n<p>\u201cElija frijoles tiernos, habas, altramuces, ma\u00edz y guisantes: hi\u00e9rvalos, junto con arroz, repollo y calabaza, picados; agregue todo a una olla grande preparada con cebolla frita en mantequilla, ajo, comino, man\u00ed molido y una pizca de az\u00facar; agregar la cuajada y la leche, y luego de hervirlo con trozos de pescado y camarones, el plato se sirve con trozos de masa frita de diferentes formas, y rodajas muy peque\u00f1as de pl\u00e1tano frito, rodajas de huevo cocido, perejil picado y pimienta molida sobre cima.\u00bb<\/p>\n<p>(Carlos Gallardo de la Fuente, Fanescas, un recorrido ancestral y contempor\u00e1neo por una tradici\u00f3n festiva del Ecuador, UDLA, 2012. Julio Pazos, El sabor de la memoria, historia de la cocina quite\u00f1a, Fonsal, 2008.)<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div>\n<div>\n<div>\n<div>\n<div>\n<div>\n<div>\n<p>Hay algunas recetas modernas que vienen sin los trozos de bacalao frito, \u00a1que quiz\u00e1s encuentres que prefieres! Y aunque la fanesca se llena bastante por s\u00ed sola, trate de dejar espacio para el postre. La fanesca tambi\u00e9n se sirve con otro cl\u00e1sico ecuatoriano: Higos con queso. Estos higos en conserva en alm\u00edbar dulce son muy sabrosos cuando se combinan con una rebanada de queso salado.<\/p>\n<p>Puedes probar la fanesca por ti mismo en excelentes restaurantes por toda la ciudad. Pero debes saber que si le pides a un quite\u00f1o sugerencias de la mejor fanesca de la zona, lo m\u00e1s probable es que te dirija a la cocina de su madre o abuela.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>La fanesca es el plato del men\u00fa festivo familiar del domingo de Pascua. Tambi\u00e9n puedes encontrarlo servido como plato especial de temporada en restaurantes y ferias gastron\u00f3micas. La fanesca es una sopa abundante hecha a base de granos tiernos y pescado seco. Para algunos, puede ser un gusto adquirido, pero para la mayor\u00eda de los [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":3917,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[2076],"tags":[],"class_list":["post-5059","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categorizar"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Fanesca - ILLA Experience hotel : luxury boutique hotel in Quito Ecuador : 5 star accommodation<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/illaexperiencehotel.com\/es\/fanesca\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fanesca - ILLA Experience hotel : luxury boutique hotel in Quito Ecuador : 5 star accommodation\" \/>\n<meta property=\"og:description\" content=\"La fanesca es el plato del men\u00fa festivo familiar del domingo de Pascua. Tambi\u00e9n puedes encontrarlo servido como plato especial de temporada en restaurantes y ferias gastron\u00f3micas. La fanesca es una sopa abundante hecha a base de granos tiernos y pescado seco. Para algunos, puede ser un gusto adquirido, pero para la mayor\u00eda de los [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/illaexperiencehotel.com\/es\/fanesca\/\" \/>\n<meta property=\"og:site_name\" content=\"ILLA Experience hotel : luxury boutique hotel in Quito Ecuador : 5 star accommodation\" \/>\n<meta property=\"article:published_time\" content=\"2018-02-12T03:55:35+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-12-29T20:04:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/illaexperiencehotel.com\/wp-content\/uploads\/2018\/03\/fanesca-ecuador1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1033\" \/>\n\t<meta property=\"og:image:height\" content=\"341\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"illa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"illa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/illaexperiencehotel.com\\\/es\\\/fanesca\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/illaexperiencehotel.com\\\/es\\\/fanesca\\\/\"},\"author\":{\"name\":\"illa\",\"@id\":\"https:\\\/\\\/illaexperiencehotel.com\\\/#\\\/schema\\\/person\\\/61748114a58267edb47d32379ddb415a\"},\"headline\":\"Fanesca\",\"datePublished\":\"2018-02-12T03:55:35+00:00\",\"dateModified\":\"2021-12-29T20:04:18+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/illaexperiencehotel.com\\\/es\\\/fanesca\\\/\"},\"wordCount\":640,\"image\":{\"@id\":\"https:\\\/\\\/illaexperiencehotel.com\\\/es\\\/fanesca\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/illaexperiencehotel.com\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/fanesca-ecuador1.jpg\",\"articleSection\":[\"Sin categorizar\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/illaexperiencehotel.com\\\/es\\\/fanesca\\\/\",\"url\":\"https:\\\/\\\/illaexperiencehotel.com\\\/es\\\/fanesca\\\/\",\"name\":\"Fanesca - ILLA Experience hotel : luxury boutique hotel in Quito Ecuador : 5 star accommodation\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/illaexperiencehotel.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/illaexperiencehotel.com\\\/es\\\/fanesca\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/illaexperiencehotel.com\\\/es\\\/fanesca\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/illaexperiencehotel.com\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/fanesca-ecuador1.jpg\",\"datePublished\":\"2018-02-12T03:55:35+00:00\",\"dateModified\":\"2021-12-29T20:04:18+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/illaexperiencehotel.com\\\/#\\\/schema\\\/person\\\/61748114a58267edb47d32379ddb415a\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/illaexperiencehotel.com\\\/es\\\/fanesca\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/illaexperiencehotel.com\\\/es\\\/fanesca\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/illaexperiencehotel.com\\\/es\\\/fanesca\\\/#primaryimage\",\"url\":\"https:\\\/\\\/illaexperiencehotel.com\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/fanesca-ecuador1.jpg\",\"contentUrl\":\"https:\\\/\\\/illaexperiencehotel.com\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/fanesca-ecuador1.jpg\",\"width\":1033,\"height\":341},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/illaexperiencehotel.com\\\/es\\\/fanesca\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/illaexperiencehotel.com\\\/es\\\/inicio-illa-experience-hotel\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Fanesca\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/illaexperiencehotel.com\\\/#website\",\"url\":\"https:\\\/\\\/illaexperiencehotel.com\\\/\",\"name\":\"ILLA Experience hotel : luxury boutique hotel in Quito Ecuador : 5 star accommodation\",\"description\":\"ILLA Experience hotel : luxury  boutique hotel in Quito Ecuador : 5 star accommodation\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/illaexperiencehotel.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/illaexperiencehotel.com\\\/#\\\/schema\\\/person\\\/61748114a58267edb47d32379ddb415a\",\"name\":\"illa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ba738f2640a90763f57c5cf1ac0992debbb5df39a5c1b492fc174f782a64b71f?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ba738f2640a90763f57c5cf1ac0992debbb5df39a5c1b492fc174f782a64b71f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ba738f2640a90763f57c5cf1ac0992debbb5df39a5c1b492fc174f782a64b71f?s=96&d=mm&r=g\",\"caption\":\"illa\"},\"url\":\"https:\\\/\\\/illaexperiencehotel.com\\\/es\\\/author\\\/illa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Fanesca - ILLA Experience hotel : luxury boutique hotel in Quito Ecuador : 5 star accommodation","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/illaexperiencehotel.com\/es\/fanesca\/","og_locale":"es_ES","og_type":"article","og_title":"Fanesca - ILLA Experience hotel : luxury boutique hotel in Quito Ecuador : 5 star accommodation","og_description":"La fanesca es el plato del men\u00fa festivo familiar del domingo de Pascua. Tambi\u00e9n puedes encontrarlo servido como plato especial de temporada en restaurantes y ferias gastron\u00f3micas. La fanesca es una sopa abundante hecha a base de granos tiernos y pescado seco. Para algunos, puede ser un gusto adquirido, pero para la mayor\u00eda de los [&hellip;]","og_url":"https:\/\/illaexperiencehotel.com\/es\/fanesca\/","og_site_name":"ILLA Experience hotel : luxury boutique hotel in Quito Ecuador : 5 star accommodation","article_published_time":"2018-02-12T03:55:35+00:00","article_modified_time":"2021-12-29T20:04:18+00:00","og_image":[{"width":1033,"height":341,"url":"https:\/\/illaexperiencehotel.com\/wp-content\/uploads\/2018\/03\/fanesca-ecuador1.jpg","type":"image\/jpeg"}],"author":"illa","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"illa","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/illaexperiencehotel.com\/es\/fanesca\/#article","isPartOf":{"@id":"https:\/\/illaexperiencehotel.com\/es\/fanesca\/"},"author":{"name":"illa","@id":"https:\/\/illaexperiencehotel.com\/#\/schema\/person\/61748114a58267edb47d32379ddb415a"},"headline":"Fanesca","datePublished":"2018-02-12T03:55:35+00:00","dateModified":"2021-12-29T20:04:18+00:00","mainEntityOfPage":{"@id":"https:\/\/illaexperiencehotel.com\/es\/fanesca\/"},"wordCount":640,"image":{"@id":"https:\/\/illaexperiencehotel.com\/es\/fanesca\/#primaryimage"},"thumbnailUrl":"https:\/\/illaexperiencehotel.com\/wp-content\/uploads\/2018\/03\/fanesca-ecuador1.jpg","articleSection":["Sin categorizar"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/illaexperiencehotel.com\/es\/fanesca\/","url":"https:\/\/illaexperiencehotel.com\/es\/fanesca\/","name":"Fanesca - ILLA Experience hotel : luxury boutique hotel in Quito Ecuador : 5 star accommodation","isPartOf":{"@id":"https:\/\/illaexperiencehotel.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/illaexperiencehotel.com\/es\/fanesca\/#primaryimage"},"image":{"@id":"https:\/\/illaexperiencehotel.com\/es\/fanesca\/#primaryimage"},"thumbnailUrl":"https:\/\/illaexperiencehotel.com\/wp-content\/uploads\/2018\/03\/fanesca-ecuador1.jpg","datePublished":"2018-02-12T03:55:35+00:00","dateModified":"2021-12-29T20:04:18+00:00","author":{"@id":"https:\/\/illaexperiencehotel.com\/#\/schema\/person\/61748114a58267edb47d32379ddb415a"},"breadcrumb":{"@id":"https:\/\/illaexperiencehotel.com\/es\/fanesca\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/illaexperiencehotel.com\/es\/fanesca\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/illaexperiencehotel.com\/es\/fanesca\/#primaryimage","url":"https:\/\/illaexperiencehotel.com\/wp-content\/uploads\/2018\/03\/fanesca-ecuador1.jpg","contentUrl":"https:\/\/illaexperiencehotel.com\/wp-content\/uploads\/2018\/03\/fanesca-ecuador1.jpg","width":1033,"height":341},{"@type":"BreadcrumbList","@id":"https:\/\/illaexperiencehotel.com\/es\/fanesca\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/illaexperiencehotel.com\/es\/inicio-illa-experience-hotel\/"},{"@type":"ListItem","position":2,"name":"Fanesca"}]},{"@type":"WebSite","@id":"https:\/\/illaexperiencehotel.com\/#website","url":"https:\/\/illaexperiencehotel.com\/","name":"ILLA Experience hotel : luxury boutique hotel in Quito Ecuador : 5 star accommodation","description":"ILLA Experience hotel : luxury  boutique hotel in Quito Ecuador : 5 star accommodation","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/illaexperiencehotel.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/illaexperiencehotel.com\/#\/schema\/person\/61748114a58267edb47d32379ddb415a","name":"illa","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/ba738f2640a90763f57c5cf1ac0992debbb5df39a5c1b492fc174f782a64b71f?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ba738f2640a90763f57c5cf1ac0992debbb5df39a5c1b492fc174f782a64b71f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ba738f2640a90763f57c5cf1ac0992debbb5df39a5c1b492fc174f782a64b71f?s=96&d=mm&r=g","caption":"illa"},"url":"https:\/\/illaexperiencehotel.com\/es\/author\/illa\/"}]}},"_links":{"self":[{"href":"https:\/\/illaexperiencehotel.com\/es\/wp-json\/wp\/v2\/posts\/5059","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/illaexperiencehotel.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/illaexperiencehotel.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/illaexperiencehotel.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/illaexperiencehotel.com\/es\/wp-json\/wp\/v2\/comments?post=5059"}],"version-history":[{"count":0,"href":"https:\/\/illaexperiencehotel.com\/es\/wp-json\/wp\/v2\/posts\/5059\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/illaexperiencehotel.com\/es\/wp-json\/wp\/v2\/media\/3917"}],"wp:attachment":[{"href":"https:\/\/illaexperiencehotel.com\/es\/wp-json\/wp\/v2\/media?parent=5059"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/illaexperiencehotel.com\/es\/wp-json\/wp\/v2\/categories?post=5059"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/illaexperiencehotel.com\/es\/wp-json\/wp\/v2\/tags?post=5059"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}