{"id":5048,"date":"2017-12-14T23:42:15","date_gmt":"2017-12-14T23:42:15","guid":{"rendered":"https:\/\/illaexperiencehotel.com\/un-edificio-conceptualmente-restaurado-en-el-centro-historico-de-quito\/"},"modified":"2021-12-29T19:51:50","modified_gmt":"2021-12-29T19:51:50","slug":"un-edificio-conceptualmente-restaurado-en-el-centro-historico-de-quito","status":"publish","type":"post","link":"https:\/\/illaexperiencehotel.com\/es\/un-edificio-conceptualmente-restaurado-en-el-centro-historico-de-quito\/","title":{"rendered":"Un edificio conceptualmente restaurado en el Centro Hist\u00f3rico de Quito"},"content":{"rendered":"<div>\n<div>\n<div>\n<div>\n<div>\n<div>\n<div>\n<div>\n<div>\n<div>\n<div>\n<div>\n<p>\u201cCuando entras, es como si tuvieras que desnudar la casa\u201d, dice Alexandra Chac\u00f3n Reyes, quien, junto con Wilson Mogro Miranda del estudio cero80 arquitectura, restaur\u00f3 el edificio que ahora es Hotel Illa. La estructura, como todos los dem\u00e1s edificios hist\u00f3ricos, llevaba las marcas de varias generaciones de cambios. Parte de lo que tienes que hacer cuando \u201crestauras\u201d una casa es volver de alguna manera a su intenci\u00f3n original.<img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/illaexperiencehotel.com\/wp-content\/uploads\/2017\/12\/the-illas-house2.jpg\" sizes=\"(max-width: 298px) 100vw, 298px\" srcset=\"https:\/\/illaexperiencehotel.com\/wp-content\/uploads\/2017\/12\/the-illas-house2.jpg 298w, https:\/\/illaexperiencehotel.com\/wp-content\/uploads\/2017\/12\/the-illas-house2-230x300.jpg 230w\" alt=\"Illa Experience Hotel Quito\" width=\"298\" height=\"388\"><\/p>\n<p>\u201cConsideramos la casa como un documento de cultura material\u201d, dice. El edificio cuenta la historia de todas las personas que han vivido en \u00e9l y las adaptaciones que han realizado seg\u00fan sus necesidades. \u00abTienes que leerlo en capas\u00bb.<\/p>\n<p>Restaurar casas antiguas siempre es complejo. \u00abEs un proceso diferente, trabajar en un monumento, por ejemplo, frente a un edificio destinado al uso diario\u00bb, explica Wilson. Si es un monumento, entonces el proceso de restauraci\u00f3n funciona para preservar un significado espec\u00edfico, un momento particular en el tiempo. Pero para un edificio como este, todos los diferentes momentos hist\u00f3ricos reflejados en el edificio deben tener el mismo valor.<img decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/illaexperiencehotel.com\/wp-content\/uploads\/2017\/12\/the-illas-house3.jpg\" sizes=\"(max-width: 298px) 100vw, 298px\" srcset=\"https:\/\/illaexperiencehotel.com\/wp-content\/uploads\/2017\/12\/the-illas-house3.jpg 298w, https:\/\/illaexperiencehotel.com\/wp-content\/uploads\/2017\/12\/the-illas-house3-230x300.jpg 230w\" alt=\"Illa Experience Hotel Centro Hist\u00f3rico\" width=\"298\" height=\"388\"><\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div>\n<div>\n<div>\n<div>\n<div>\n<div>\n<p>Despu\u00e9s de realizar varias visitas a la propiedad, Alexandra y Wilson comenzaron a hacer conjeturas fundamentadas sobre por qu\u00e9 se hab\u00edan realizado ciertas intervenciones y a tomar decisiones sobre qu\u00e9 cambios en el edificio podr\u00edan justificarse dentro de los requisitos de preservaci\u00f3n del patrimonio cultural. \u00abEl tiempo no valida todo\u00bb, explica. \u00abTienes que encontrar un equilibrio entre lo que es fiel a la estructura original y la funci\u00f3n contempor\u00e1nea\u00bb. Una vez que comenzaron a descubrir la historia de la casa, qued\u00f3 claro qu\u00e9 estructuras arquitect\u00f3nicas se originaron a partir del dise\u00f1o y la intenci\u00f3n del edificio, y qu\u00e9 estructuras hab\u00edan sido cambios improvisados \u200b\u200bpara adaptarse a las necesidades de los ocupantes de una \u00e9poca en particular.<\/p>\n<p>Descubrieron que la casa original probablemente se remonta al a\u00f1o 1700. El dise\u00f1o b\u00e1sico habr\u00eda sido de estilo colonial, con columnas de piedra alrededor de un patio central. Pero a principios del siglo XX, (entre 1910 y 1920, los arquitectos estimaron a partir de la presencia de ciertos elementos met\u00e1licos que solo podr\u00edan haber sido fabricados despu\u00e9s de 1910) la casa se dividi\u00f3 entre herederos, y se construy\u00f3 un muro en el patio central, esencialmente Dividiendo la casa en dos. Posteriormente, los vecinos se vieron obligados a realizar una serie de cambios funcionales en el dise\u00f1o para aprovechar lo que les quedaba: media casa y medio patio. Varias de las columnas de piedra originales se hab\u00edan eliminado, por ejemplo. Los nuevos ocupantes ya no ten\u00edan acceso a una escalera que conduc\u00eda a la parte trasera de la casa, por lo que tuvieron que construir una nueva, una que cortaba hacia el patio central.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div>\n<div>\n<div>\n<div>\n<div>\n<div>\n<p>Estos cambios coincidieron con un cambio m\u00e1s amplio en los estilos arquitect\u00f3nicos. \u201cA fines del siglo XIX y principios del XX, Quito decidi\u00f3 lavarse la cara y convertirse en una verdadera ciudad\u201d, se r\u00ede Alexandra. El estilo republicano, como lleg\u00f3 a ser llamado, marca un alejamiento de la influencia colonial espa\u00f1ola, reflejando los nuevos lazos de la reci\u00e9n formada rep\u00fablica ecuatoriana con Francia e Italia. Las fachadas, ventanas y techos de toda la ciudad se modelan de acuerdo con estos nuevos gustos.<\/p>\n<p>Los arquitectos decidieron restaurar el edificio de tal manera que contara la historia de la casa y al mismo tiempo le permitiera cumplir su funci\u00f3n contempor\u00e1nea. Se restaur\u00f3 la planta baja como un patio colonial, tal y como estaba originalmente: se quit\u00f3 la escalera que daba al patio y se devolvieron las columnas de piedra. El primer piso fue restaurado como una mansi\u00f3n de la era republicana, como lo habr\u00eda sido en esa \u00e9poca. Fueron devueltos. Se coloc\u00f3 una nueva escalera discretamente en la esquina trasera del edificio para invitar a los invitados a entrar.<img decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/illaexperiencehotel.com\/wp-content\/uploads\/2017\/12\/the-illas-house4.jpg\" sizes=\"(max-width: 298px) 100vw, 298px\" srcset=\"https:\/\/illaexperiencehotel.com\/wp-content\/uploads\/2017\/12\/the-illas-house4.jpg 298w, https:\/\/illaexperiencehotel.com\/wp-content\/uploads\/2017\/12\/the-illas-house4-230x300.jpg 230w\" alt=\"Illa Experience Hotel Quito Centro Hist\u00f3rico\" width=\"298\" height=\"388\"><\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div>\n<div>\n<div>\n<div>\n<div>\n<div>\n<p>Pero los arquitectos entendieron algo m\u00e1s sobre su intervenci\u00f3n arquitect\u00f3nica: est\u00e1 sucediendo en el presente. Si el dise\u00f1o de la restauraci\u00f3n ten\u00eda como objetivo reconocer el valor de cada per\u00edodo de tiempo representado en la historia del edificio, tambi\u00e9n era necesario reconocer el momento actual, la era contempor\u00e1nea. El segundo piso del edificio est\u00e1 dise\u00f1ado de acuerdo con un estilo arquitect\u00f3nico contempor\u00e1neo, agregando otro cap\u00edtulo a la historia de esta notable casa.<\/p>\n<p>La restauraci\u00f3n final expone las capas hist\u00f3ricas de la construcci\u00f3n del edificio, una vivisecci\u00f3n arqueol\u00f3gica de la arquitectura colonial, republicana y contempor\u00e1nea que forman un dise\u00f1o cohesivo y funcional. Illa Experience Hotel trae el pasado al presente.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>\u201cCuando entras, es como si tuvieras que desnudar la casa\u201d, dice Alexandra Chac\u00f3n Reyes, quien, junto con Wilson Mogro Miranda del estudio cero80 arquitectura, restaur\u00f3 el edificio que ahora es Hotel Illa. La estructura, como todos los dem\u00e1s edificios hist\u00f3ricos, llevaba las marcas de varias generaciones de cambios. Parte de lo que tienes que hacer [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":3831,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[2076],"tags":[],"class_list":["post-5048","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categorizar"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Un edificio conceptualmente restaurado en el Centro Hist\u00f3rico de Quito - ILLA Experience hotel : luxury boutique hotel in Quito Ecuador : 5 star accommodation<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/illaexperiencehotel.com\/es\/un-edificio-conceptualmente-restaurado-en-el-centro-historico-de-quito\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Un edificio conceptualmente restaurado en el Centro Hist\u00f3rico de Quito - ILLA Experience hotel : luxury boutique hotel in Quito Ecuador : 5 star accommodation\" \/>\n<meta property=\"og:description\" content=\"\u201cCuando entras, es como si tuvieras que desnudar la casa\u201d, dice Alexandra Chac\u00f3n Reyes, quien, junto con Wilson Mogro Miranda del estudio cero80 arquitectura, restaur\u00f3 el edificio que ahora es Hotel Illa. La estructura, como todos los dem\u00e1s edificios hist\u00f3ricos, llevaba las marcas de varias generaciones de cambios. Parte de lo que tienes que hacer [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/illaexperiencehotel.com\/es\/un-edificio-conceptualmente-restaurado-en-el-centro-historico-de-quito\/\" \/>\n<meta property=\"og:site_name\" content=\"ILLA Experience hotel : luxury boutique hotel in Quito Ecuador : 5 star accommodation\" \/>\n<meta property=\"article:published_time\" content=\"2017-12-14T23:42:15+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-12-29T19:51:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/illaexperiencehotel.com\/wp-content\/uploads\/2017\/12\/the-illas-house1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1033\" \/>\n\t<meta property=\"og:image:height\" content=\"341\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"illa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"illa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/illaexperiencehotel.com\\\/es\\\/un-edificio-conceptualmente-restaurado-en-el-centro-historico-de-quito\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/illaexperiencehotel.com\\\/es\\\/un-edificio-conceptualmente-restaurado-en-el-centro-historico-de-quito\\\/\"},\"author\":{\"name\":\"illa\",\"@id\":\"https:\\\/\\\/illaexperiencehotel.com\\\/#\\\/schema\\\/person\\\/61748114a58267edb47d32379ddb415a\"},\"headline\":\"Un edificio conceptualmente restaurado en el Centro Hist\u00f3rico de Quito\",\"datePublished\":\"2017-12-14T23:42:15+00:00\",\"dateModified\":\"2021-12-29T19:51:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/illaexperiencehotel.com\\\/es\\\/un-edificio-conceptualmente-restaurado-en-el-centro-historico-de-quito\\\/\"},\"wordCount\":794,\"image\":{\"@id\":\"https:\\\/\\\/illaexperiencehotel.com\\\/es\\\/un-edificio-conceptualmente-restaurado-en-el-centro-historico-de-quito\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/illaexperiencehotel.com\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/the-illas-house1.jpg\",\"articleSection\":[\"Sin categorizar\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/illaexperiencehotel.com\\\/es\\\/un-edificio-conceptualmente-restaurado-en-el-centro-historico-de-quito\\\/\",\"url\":\"https:\\\/\\\/illaexperiencehotel.com\\\/es\\\/un-edificio-conceptualmente-restaurado-en-el-centro-historico-de-quito\\\/\",\"name\":\"Un edificio conceptualmente restaurado en el Centro Hist\u00f3rico de Quito - ILLA Experience hotel : luxury boutique hotel in Quito Ecuador : 5 star accommodation\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/illaexperiencehotel.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/illaexperiencehotel.com\\\/es\\\/un-edificio-conceptualmente-restaurado-en-el-centro-historico-de-quito\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/illaexperiencehotel.com\\\/es\\\/un-edificio-conceptualmente-restaurado-en-el-centro-historico-de-quito\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/illaexperiencehotel.com\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/the-illas-house1.jpg\",\"datePublished\":\"2017-12-14T23:42:15+00:00\",\"dateModified\":\"2021-12-29T19:51:50+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/illaexperiencehotel.com\\\/#\\\/schema\\\/person\\\/61748114a58267edb47d32379ddb415a\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/illaexperiencehotel.com\\\/es\\\/un-edificio-conceptualmente-restaurado-en-el-centro-historico-de-quito\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/illaexperiencehotel.com\\\/es\\\/un-edificio-conceptualmente-restaurado-en-el-centro-historico-de-quito\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/illaexperiencehotel.com\\\/es\\\/un-edificio-conceptualmente-restaurado-en-el-centro-historico-de-quito\\\/#primaryimage\",\"url\":\"https:\\\/\\\/illaexperiencehotel.com\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/the-illas-house1.jpg\",\"contentUrl\":\"https:\\\/\\\/illaexperiencehotel.com\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/the-illas-house1.jpg\",\"width\":1033,\"height\":341},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/illaexperiencehotel.com\\\/es\\\/un-edificio-conceptualmente-restaurado-en-el-centro-historico-de-quito\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/illaexperiencehotel.com\\\/es\\\/inicio-illa-experience-hotel\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Un edificio conceptualmente restaurado en el Centro Hist\u00f3rico de Quito\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/illaexperiencehotel.com\\\/#website\",\"url\":\"https:\\\/\\\/illaexperiencehotel.com\\\/\",\"name\":\"ILLA Experience hotel : luxury boutique hotel in Quito Ecuador : 5 star accommodation\",\"description\":\"ILLA Experience hotel : luxury  boutique hotel in Quito Ecuador : 5 star accommodation\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/illaexperiencehotel.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/illaexperiencehotel.com\\\/#\\\/schema\\\/person\\\/61748114a58267edb47d32379ddb415a\",\"name\":\"illa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ba738f2640a90763f57c5cf1ac0992debbb5df39a5c1b492fc174f782a64b71f?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ba738f2640a90763f57c5cf1ac0992debbb5df39a5c1b492fc174f782a64b71f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ba738f2640a90763f57c5cf1ac0992debbb5df39a5c1b492fc174f782a64b71f?s=96&d=mm&r=g\",\"caption\":\"illa\"},\"url\":\"https:\\\/\\\/illaexperiencehotel.com\\\/es\\\/author\\\/illa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Un edificio conceptualmente restaurado en el Centro Hist\u00f3rico de Quito - ILLA Experience hotel : luxury boutique hotel in Quito Ecuador : 5 star accommodation","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/illaexperiencehotel.com\/es\/un-edificio-conceptualmente-restaurado-en-el-centro-historico-de-quito\/","og_locale":"es_ES","og_type":"article","og_title":"Un edificio conceptualmente restaurado en el Centro Hist\u00f3rico de Quito - ILLA Experience hotel : luxury boutique hotel in Quito Ecuador : 5 star accommodation","og_description":"\u201cCuando entras, es como si tuvieras que desnudar la casa\u201d, dice Alexandra Chac\u00f3n Reyes, quien, junto con Wilson Mogro Miranda del estudio cero80 arquitectura, restaur\u00f3 el edificio que ahora es Hotel Illa. La estructura, como todos los dem\u00e1s edificios hist\u00f3ricos, llevaba las marcas de varias generaciones de cambios. Parte de lo que tienes que hacer [&hellip;]","og_url":"https:\/\/illaexperiencehotel.com\/es\/un-edificio-conceptualmente-restaurado-en-el-centro-historico-de-quito\/","og_site_name":"ILLA Experience hotel : luxury boutique hotel in Quito Ecuador : 5 star accommodation","article_published_time":"2017-12-14T23:42:15+00:00","article_modified_time":"2021-12-29T19:51:50+00:00","og_image":[{"width":1033,"height":341,"url":"https:\/\/illaexperiencehotel.com\/wp-content\/uploads\/2017\/12\/the-illas-house1.jpg","type":"image\/jpeg"}],"author":"illa","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"illa","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/illaexperiencehotel.com\/es\/un-edificio-conceptualmente-restaurado-en-el-centro-historico-de-quito\/#article","isPartOf":{"@id":"https:\/\/illaexperiencehotel.com\/es\/un-edificio-conceptualmente-restaurado-en-el-centro-historico-de-quito\/"},"author":{"name":"illa","@id":"https:\/\/illaexperiencehotel.com\/#\/schema\/person\/61748114a58267edb47d32379ddb415a"},"headline":"Un edificio conceptualmente restaurado en el Centro Hist\u00f3rico de Quito","datePublished":"2017-12-14T23:42:15+00:00","dateModified":"2021-12-29T19:51:50+00:00","mainEntityOfPage":{"@id":"https:\/\/illaexperiencehotel.com\/es\/un-edificio-conceptualmente-restaurado-en-el-centro-historico-de-quito\/"},"wordCount":794,"image":{"@id":"https:\/\/illaexperiencehotel.com\/es\/un-edificio-conceptualmente-restaurado-en-el-centro-historico-de-quito\/#primaryimage"},"thumbnailUrl":"https:\/\/illaexperiencehotel.com\/wp-content\/uploads\/2017\/12\/the-illas-house1.jpg","articleSection":["Sin categorizar"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/illaexperiencehotel.com\/es\/un-edificio-conceptualmente-restaurado-en-el-centro-historico-de-quito\/","url":"https:\/\/illaexperiencehotel.com\/es\/un-edificio-conceptualmente-restaurado-en-el-centro-historico-de-quito\/","name":"Un edificio conceptualmente restaurado en el Centro Hist\u00f3rico de Quito - ILLA Experience hotel : luxury boutique hotel in Quito Ecuador : 5 star accommodation","isPartOf":{"@id":"https:\/\/illaexperiencehotel.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/illaexperiencehotel.com\/es\/un-edificio-conceptualmente-restaurado-en-el-centro-historico-de-quito\/#primaryimage"},"image":{"@id":"https:\/\/illaexperiencehotel.com\/es\/un-edificio-conceptualmente-restaurado-en-el-centro-historico-de-quito\/#primaryimage"},"thumbnailUrl":"https:\/\/illaexperiencehotel.com\/wp-content\/uploads\/2017\/12\/the-illas-house1.jpg","datePublished":"2017-12-14T23:42:15+00:00","dateModified":"2021-12-29T19:51:50+00:00","author":{"@id":"https:\/\/illaexperiencehotel.com\/#\/schema\/person\/61748114a58267edb47d32379ddb415a"},"breadcrumb":{"@id":"https:\/\/illaexperiencehotel.com\/es\/un-edificio-conceptualmente-restaurado-en-el-centro-historico-de-quito\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/illaexperiencehotel.com\/es\/un-edificio-conceptualmente-restaurado-en-el-centro-historico-de-quito\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/illaexperiencehotel.com\/es\/un-edificio-conceptualmente-restaurado-en-el-centro-historico-de-quito\/#primaryimage","url":"https:\/\/illaexperiencehotel.com\/wp-content\/uploads\/2017\/12\/the-illas-house1.jpg","contentUrl":"https:\/\/illaexperiencehotel.com\/wp-content\/uploads\/2017\/12\/the-illas-house1.jpg","width":1033,"height":341},{"@type":"BreadcrumbList","@id":"https:\/\/illaexperiencehotel.com\/es\/un-edificio-conceptualmente-restaurado-en-el-centro-historico-de-quito\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/illaexperiencehotel.com\/es\/inicio-illa-experience-hotel\/"},{"@type":"ListItem","position":2,"name":"Un edificio conceptualmente restaurado en el Centro Hist\u00f3rico de Quito"}]},{"@type":"WebSite","@id":"https:\/\/illaexperiencehotel.com\/#website","url":"https:\/\/illaexperiencehotel.com\/","name":"ILLA Experience hotel : luxury boutique hotel in Quito Ecuador : 5 star accommodation","description":"ILLA Experience hotel : luxury  boutique hotel in Quito Ecuador : 5 star accommodation","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/illaexperiencehotel.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/illaexperiencehotel.com\/#\/schema\/person\/61748114a58267edb47d32379ddb415a","name":"illa","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/ba738f2640a90763f57c5cf1ac0992debbb5df39a5c1b492fc174f782a64b71f?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ba738f2640a90763f57c5cf1ac0992debbb5df39a5c1b492fc174f782a64b71f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ba738f2640a90763f57c5cf1ac0992debbb5df39a5c1b492fc174f782a64b71f?s=96&d=mm&r=g","caption":"illa"},"url":"https:\/\/illaexperiencehotel.com\/es\/author\/illa\/"}]}},"_links":{"self":[{"href":"https:\/\/illaexperiencehotel.com\/es\/wp-json\/wp\/v2\/posts\/5048","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/illaexperiencehotel.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/illaexperiencehotel.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/illaexperiencehotel.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/illaexperiencehotel.com\/es\/wp-json\/wp\/v2\/comments?post=5048"}],"version-history":[{"count":0,"href":"https:\/\/illaexperiencehotel.com\/es\/wp-json\/wp\/v2\/posts\/5048\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/illaexperiencehotel.com\/es\/wp-json\/wp\/v2\/media\/3831"}],"wp:attachment":[{"href":"https:\/\/illaexperiencehotel.com\/es\/wp-json\/wp\/v2\/media?parent=5048"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/illaexperiencehotel.com\/es\/wp-json\/wp\/v2\/categories?post=5048"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/illaexperiencehotel.com\/es\/wp-json\/wp\/v2\/tags?post=5048"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}